{"id":2618,"date":"2017-08-06T20:17:33","date_gmt":"2017-08-07T01:17:33","guid":{"rendered":"http:\/\/solara-surf-report.com\/de\/2017\/08\/forged-in-fire\/"},"modified":"2017-09-16T19:50:32","modified_gmt":"2017-09-17T00:50:32","slug":"im-feuer-geschmiedet","status":"publish","type":"post","link":"https:\/\/solara-surf-report.com\/de\/2017\/08\/im-feuer-geschmiedet\/","title":{"rendered":"Solara&#8217;s August 2017 Surf Report &#8211; Geschmiedet im Feuer der Verwandlung"},"content":{"rendered":"<div class=\"passster-form\" id=\"ps-614\">\n    <form class=\"password-form\" method=\"post\" autocomplete=\"off\" target=\"_top\">\n        <h4>Protected Area<\/h4>\n        <p>This content is password-protected. Please verify with a password to unlock the content.<\/p>\n        <fieldset>\n            <span class=\"ps-loader\"><img src=\"https:\/\/solara-surf-report.com\/wp-content\/plugins\/content-protector\/assets\/public\/ps-loader.svg\"\/><\/span>\n            <label for=\"passster_password\" style=\"display:none;\">Enter your password<\/label>\n            <input placeholder=\"Enter your password..\" type=\"password\" tabindex=\"1\" name=\"passster_password\"\n                   id=\"passster_password\" class=\"passster-password\" autocomplete=\"off\"\n                   data-protection-type=\"password\" data-list=\"[PASSSTER_LIST]\" data-area=\"[PASSSTER_AREA]\"\n                   data-protection=\"[PASSSTER_PROTECTION]\">\n            \n            <button name=\"submit\" type=\"submit\" class=\"passster-submit\" data-psid=\"ps-614\" \n                    data-submit=\"...Checking Password\" data-redirect=\"\">Unlock\n            <\/button>\n            <div class=\"passster-error\"><\/div>\n        <\/fieldset>\n    <\/form>\n<\/div><p style=\"text-align: center;\"><img class=\"aligncenter size-full wp-image-190\" title=\"waves1\" src=\"http:\/\/solara-surf-report.com\/wp-content\/uploads\/2015\/12\/waves1.gif\" alt=\"waves1\" width=\"400\" height=\"20\" \/><\/p>\r\n<p style=\"text-align: center;\">Solara's Monatliche Surf Reports & Updates k\u00f6nnen abonniert werden\r\nf\u00fcr 11 USD (mit Updates) in Englisch, Deutsch, Spanisch und Russisch<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/mercado.nvisible.com\/surf-report-subscriptions\/\" target=\"_blank\">Abonniere hier ...<\/a><\/p>\r\n&nbsp;\r\n\r\n[aesop_chapter title=\"Die Karten von AN\" bgtype=\"img\" full=\"off\"]\r\n\r\n&nbsp;\r\n<p style=\"text-align: center;\"><img class=\"aligncenter wp-image-16 size-medium\" title=\"2015-12-30-Cards-1015\" src=\"http:\/\/solara-surf-report.com\/wp-content\/uploads\/2015\/12\/2015-12-30-Cards-1015-400x267.jpg\" alt=\"2015-12-30-Cards-1015\" width=\"400\" height=\"267\" \/><\/p>\r\n<p style=\"text-align: center;\">Solara's Karten von AN sind endlich erh\u00e4ltlich!<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #ff00ff;\">Ein gro\u00dfartiges, lebendiges, interaktives und extrem effektives Werkzeug\r\nzur Verankerung der Neuen Realit\u00e4t.\r\nEs ist wie ein ma\u00dfgeschneiderter, pers\u00f6nlicher Surf-Report!<\/span><\/p>\r\n<p style=\"text-align: center;\">Die Karten von AN bestehen aus einem 152-seitigen Buch <em>(derzeit nur in englischer Sprache)<\/em>,\r\nund vier einzigartigen Kartenstapeln,\r\ndie einem Einsichten von erstaunlicher Korrektheit auf vielen verschiedenen Ebenen vermitteln.\r\nKarten und Buch sind in einer wunderbaren, handgen\u00e4hten Tasche\r\n'aus handgewebtem Peruanischen Bayeta-Wollstoff mit einem Brokatfutter in verschiedenen Farben\r\nund einer kleineren Tasche f\u00fcr die Karten.<\/p>\r\n<p style=\"text-align: center;\">Du kannst die Karten von AN hier bestellen:<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/an-mercado.nvisible.com\" target=\"_blank\">an-mercado.nvisible.com<\/a><\/p>\r\n<p style=\"text-align: center;\"><img class=\"aligncenter wp-image-265 size-medium\" title=\"2015-09-01-CB-1007\" src=\"http:\/\/solara-surf-report.com\/wp-content\/uploads\/2017\/02\/The-Cards-Packages-400x226.jpg\" alt=\"2015-09-01-CB-1007\" width=\"400\" height=\"226\" \/><\/p>\r\n\r\n\r\n<hr class=\"ema_hr_magenta ema_80_5\" \/>\r\n\r\n<h2 style=\"text-align: center;\">BITTE BESUCHE UNSERE SPANNENDEN WEBSEITEN!<\/h2>\r\n<p style=\"text-align: center;\"><a href=\"\/?p=324\" target=\"_blank\">Solara's Surf-Report f\u00fcr 2017 - Sich Engagieren und Wahrhaft Leben<\/a><\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/anvisible.com\/de\/\" target=\"_blank\">The AN\u2022visible:<\/a> Die Webseite von AN und dem Herz-von-AN-Zentrum in Peru (in Deutsch)<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/mercado.nvisible.com\" target=\"_blank\">The Nvisible Mercado:<\/a> Musik, B\u00fccher, Meditationen, Surf-Report-Abonnements<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/an-mercado.nvisible.com\" target=\"_blank\">The AN\u2022Mercado:<\/a> Solara's Karten von AN, Peruanische Kostbarkeiten<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/journey.emanaku.com\/de\/\" target=\"_blank\">11:11 Photo Journeys:<\/a> Wundervolle Reisen in Bildern durch alle 11:11-Aktivierungen (in Deutsch)<\/p>\r\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.nvisible.com\/deutsch\/indexde.html\" target=\"_blank\">The Nvisible:<\/a> Solara und 11:11 (in Deutsch)<\/p>\r\n<p style=\"text-align: center;\"><em>und auf Facebook:\r\n<\/em><a href=\"https:\/\/www.facebook.com\/groups\/162204737312932\/\" target=\"_blank\">The Heart of AN<\/a> ~ <a href=\"https:\/\/www.facebook.com\/1111Doorway\/\" target=\"_blank\">11:11 Doorway<\/a> ~ <a href=\"https:\/\/www.facebook.com\/SolaraANAmua\/\" target=\"_blank\">Solara<\/a> ~ <a href=\"https:\/\/www.facebook.com\/groups\/Sebastian1111\/\" target=\"_blank\">11:11 Torweg (in Deutsch)<\/a><\/p>\r\n\r\n\r\n<hr class=\"ema_hr_magenta ema_80_5\" \/>\n","protected":false},"excerpt":{"rendered":"<p>August ist ein gr\u00f6\u00dferer Wendepunkt des NICHT AUFGEBEN &#8211; KEIN ZUR\u00dcCK. Vielen von uns wird klar werden, dass wir das offensichtliche Ende eines langen Zyklus erreicht haben, und dass wir nicht mehr zur\u00fcck kehren k\u00f6nnen zu &#8222;Wie Die Dinge Immer Waren&#8220;. Das wird bewirken, dass alles, was wir gewu\u00dft haben, einer ungeheuren Neu-Strukturierung unterliegen wird, und deshalb werden wir eine Menge innerer und \u00e4u\u00dferer Anpassungen vornehmen. Immer wieder sto\u00dfen wir vielleicht auf Senkl\u00f6cher, wenn Segmente dessen, was immer immer f\u00fcr wahr gehalten hatten, pl\u00f6tzlich hinweg fallen. Nach dem August wird nichts mehr das Gleiche sein.<\/p>\n<p>Es ist komisch, wie immer mehr Menschen jetzt innerlich freier werden, w\u00e4hrend wir im gleichen Moment immer weniger \u00e4u\u00dfere Freiheiten haben. Dies sollte uns vielleicht mehr Sorgen machen, als es derzeit tut. Ich selbst habe das Gef\u00fchl, dass wir einfach zu gro\u00df gewachsen sind, als dass wir noch in die Beschr\u00e4nkungen hinein passen, die uns auferlegt werden, und wir werden unsere illusion\u00e4ren Fesseln einfach sprengen. Weite Wesen wie wir es sind k\u00f6nnen nicht beschr\u00e4nkt werden. Das w\u00e4re wie wenn man Handschellen anlegt &#8211; an leere Kleidung.<\/p>\n","protected":false},"author":2,"featured_media":2518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"passster_activate_protection":false,"passster_protect_child_pages":"","passster_protection_type":"password","passster_password":"","passster_activate_overwrite_defaults":"","passster_headline":"","passster_instruction":"","passster_placeholder":"","passster_button":"","passster_id":"","passster_activate_misc_settings":"","passster_redirect_url":"","passster_hide":"no","passster_area_shortcode":""},"categories":[28],"tags":[38],"_links":{"self":[{"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/posts\/2618"}],"collection":[{"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/comments?post=2618"}],"version-history":[{"count":8,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/posts\/2618\/revisions"}],"predecessor-version":[{"id":2806,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/posts\/2618\/revisions\/2806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/media\/2518"}],"wp:attachment":[{"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/media?parent=2618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/categories?post=2618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solara-surf-report.com\/de\/wp-json\/wp\/v2\/tags?post=2618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}